{"id":57,"date":"2018-07-06T14:46:35","date_gmt":"2018-07-06T14:46:35","guid":{"rendered":"https:\/\/wpmu.azurewebsites.net\/nlt\/?page_id=57"},"modified":"2018-07-06T14:46:35","modified_gmt":"2018-07-06T14:46:35","slug":"audio-samples","status":"publish","type":"page","link":"https:\/\/sites.tyndale.com\/nlt\/audio-samples\/","title":{"rendered":"Written to be Spoken"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/sites.tyndale.com\/nlt\/wp-json\/wp\/v2\/pages\/57"}],"collection":[{"href":"https:\/\/sites.tyndale.com\/nlt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sites.tyndale.com\/nlt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sites.tyndale.com\/nlt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.tyndale.com\/nlt\/wp-json\/wp\/v2\/comments?post=57"}],"version-history":[{"count":0,"href":"https:\/\/sites.tyndale.com\/nlt\/wp-json\/wp\/v2\/pages\/57\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.tyndale.com\/nlt\/wp-json\/wp\/v2\/media?parent=57"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}