{"id":191,"count":1,"description":"","link":"https:\/\/sites.tyndale.com\/nlt\/tag\/psalm-22\/","name":"Psalm 22","slug":"psalm-22","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/sites.tyndale.com\/nlt\/wp-json\/wp\/v2\/tags\/191"}],"collection":[{"href":"https:\/\/sites.tyndale.com\/nlt\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/sites.tyndale.com\/nlt\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/sites.tyndale.com\/nlt\/wp-json\/wp\/v2\/posts?tags=191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}