{"id":194,"count":6,"description":"","link":"https:\/\/sites.tyndale.com\/nlt\/tag\/psalm-91\/","name":"Psalm 91","slug":"psalm-91","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/sites.tyndale.com\/nlt\/wp-json\/wp\/v2\/tags\/194"}],"collection":[{"href":"https:\/\/sites.tyndale.com\/nlt\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/sites.tyndale.com\/nlt\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/sites.tyndale.com\/nlt\/wp-json\/wp\/v2\/posts?tags=194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}