{"id":105,"count":1,"description":"","link":"https:\/\/sites.tyndale.com\/tyndalebibles\/tag\/resources\/","name":"Resources","slug":"resources","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/sites.tyndale.com\/tyndalebibles\/wp-json\/wp\/v2\/tags\/105"}],"collection":[{"href":"https:\/\/sites.tyndale.com\/tyndalebibles\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/sites.tyndale.com\/tyndalebibles\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/sites.tyndale.com\/tyndalebibles\/wp-json\/wp\/v2\/posts?tags=105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}